{"id":323,"date":"2024-09-24T07:59:37","date_gmt":"2024-09-24T07:59:37","guid":{"rendered":"https:\/\/sot.dev32.de\/?page_id=323"},"modified":"2024-11-19T10:44:38","modified_gmt":"2024-11-19T10:44:38","slug":"per-bus","status":"publish","type":"page","link":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/","title":{"rendered":"Tours by bus"},"content":{"rendered":"[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;4.24.2&#8243; background_color=&#8220;rgba(0,0,0,0.46)&#8220; background_image=&#8220;https:\/\/simply-out-tours.de\/wp-content\/uploads\/2024\/09\/simply-out-tours-089.jpg&#8220; background_blend=&#8220;multiply&#8220; width=&#8220;99%&#8220; module_alignment=&#8220;center&#8220; custom_margin=&#8220;10px|10px|10px|10px|false|false&#8220; da_disable_devices=&#8220;off|off|off&#8220; border_radii=&#8220;off||100px||100px&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text admin_label=&#8220;Text&#8220; _builder_version=&#8220;4.24.2&#8243; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;46px&#8220; header_text_color=&#8220;#FFFFFF&#8220; header_font_size=&#8220;43px&#8220; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; text_orientation=&#8220;center&#8220; global_colors_info=&#8220;{}&#8220; custom_padding_phone=&#8220;14px||14px||true|false&#8220; custom_padding_last_edited=&#8220;on|phone&#8220;]<h1>Per Bus<\/h1>\n<p><\/p>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 109px; top: -1.0625px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;90px||90px||true|&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; custom_padding_tablet=&#8220;40px||40px||true|false&#8220; custom_padding_phone=&#8220;0px||0px||true|false&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row column_structure=&#8220;3_5,2_5&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; text_font=&#8220;||||||||&#8220; text_text_color=&#8220;#000000&#8243; text_font_size=&#8220;18px&#8220; header_font=&#8220;||||||||&#8220; header_2_font=&#8220;|600|||||||&#8220; header_2_text_color=&#8220;#6ccce2&#8243; global_colors_info=&#8220;{}&#8220;]<h2 class=\"elementor-heading-title elementor-size-default\">Kreuz und quer durch den Pott \u2013 nachhaltig per Bus unterwegs<\/h2>\n<p>Erlebt das Ruhrgebiet bequem und umweltfreundlich auf einer Bustour quer durch die Region! Mit unseren individuell geplanten Touren erkunden wir die spannendsten Ecken des Ruhrgebiets, ideal f\u00fcr gr\u00f6\u00dfere Gruppen, die effizient und nachhaltig gef\u00fchrt werden m\u00f6chten. Von Industriedenkm\u00e4lern bis hin zu unseren &#8222;Alpen&#8220; \u2013 den Halden \u2013 nehmen wir euch mit auf eine Reise, die bleibt.<\/p>\n<p>Ob Betriebsausflug, Vereinstour oder Familientag \u2013 wir gestalten die Tour genau nach euren W\u00fcnschen und passen uns der Gruppengr\u00f6\u00dfe an. Ihr habt die Wahl, ob ihr einen eigenen Reisebus mitbringt oder wir einen Bus f\u00fcr euch organisieren. Und das Beste: Auf Wunsch steigen wir an ausgew\u00e4hlten Sehensw\u00fcrdigkeiten aus, um eine kurze F\u00fchrung einzulegen und die Highlights aus der N\u00e4he zu erleben.<\/p>\n<p>Steigt ein, und lasst uns gemeinsam das Ruhrgebiet entdecken \u2013 effizient, abwechslungsreich und einfach besonders!<\/p>\n<p>Kontaktiere und jetzt f\u00fcr dein pers\u00f6nliches und individuelles Angebot!<\/p>\n<p>&nbsp;<\/p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; da_disable_devices=&#8220;off|off|off&#8220; global_colors_info=&#8220;{}&#8220; da_is_popup=&#8220;off&#8220; da_exit_intent=&#8220;off&#8220; da_has_close=&#8220;on&#8220; da_alt_close=&#8220;off&#8220; da_dark_close=&#8220;off&#8220; da_not_modal=&#8220;on&#8220; da_is_singular=&#8220;off&#8220; da_with_loader=&#8220;off&#8220; da_has_shadow=&#8220;on&#8220;][et_pb_row _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code _builder_version=&#8220;4.24.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]","protected":false},"excerpt":{"rendered":"<p>Per Bus Kreuz und quer durch den Pott \u2013 nachhaltig per Bus unterwegs Erlebt das Ruhrgebiet bequem und umweltfreundlich auf einer Bustour quer durch die Region! Mit unseren individuell geplanten Touren erkunden wir die spannendsten Ecken des Ruhrgebiets, ideal f\u00fcr gr\u00f6\u00dfere Gruppen, die effizient und nachhaltig gef\u00fchrt werden m\u00f6chten. Von Industriedenkm\u00e4lern bis hin zu unseren [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":22,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:divi\/placeholder \/-->","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-323","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ein \u00dcberblick \u00fcber unsere Touren &quot;mit dem Bus&quot; durch das Ruhrgebiet\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/per-bus\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en#listItem\",\"position\":1,\"name\":\"Zu Hause\",\"item\":\"https:\\\/\\\/simply-out-tours.de\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/#listItem\",\"name\":\"Touren f\\u00fcr private Gruppen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/#listItem\",\"position\":2,\"name\":\"Touren f\\u00fcr private Gruppen\",\"item\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/per-bus\\\/#listItem\",\"name\":\"Per Bus\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en#listItem\",\"name\":\"Zu Hause\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/per-bus\\\/#listItem\",\"position\":3,\"name\":\"Per Bus\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/#listItem\",\"name\":\"Touren f\\u00fcr private Gruppen\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/#organization\",\"name\":\"simply out tours - simply out tours\",\"description\":\"gef\\u00fchrte Touren und Sightseeing im Ruhrgebiet - simply out tours\",\"url\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/\",\"email\":\"info@simply-out-tours.de\",\"telephone\":\"+4923433847440\",\"foundingDate\":\"2022-11-22\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"value\":1},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/simply-out-tours.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/SOT-small.png\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/per-bus\\\/#organizationLogo\",\"width\":688,\"height\":413,\"caption\":\"Logo von simply out tours GmbH \\u2013 Anbieter f\\u00fcr Touren, F\\u00fchrungen und Erlebnisse rund um Industriekultur, Stadtgeschichte und Natur im Ruhrgebiet.\"},\"image\":{\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/per-bus\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/simplyouttours\",\"https:\\\/\\\/instagram.com\\\/simplyouttours\",\"https:\\\/\\\/www.youtube.com\\\/@simplyouttours.ruhrgebiet\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/36574768\\\/\",\"https:\\\/\\\/www.yelp.com\\\/biz\\\/simply-out-tours-gmbh-bochum\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/per-bus\\\/#webpage\",\"url\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/per-bus\\\/\",\"name\":\"Per Bus - simply out tours\",\"description\":\"Ein \\u00dcberblick \\u00fcber unsere Touren \\\"mit dem Bus\\\" durch das Ruhrgebiet\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/touren-fuer-private-gruppen\\\/per-bus\\\/#breadcrumblist\"},\"datePublished\":\"2024-09-24T07:59:37+01:00\",\"dateModified\":\"2024-11-19T10:44:38+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/\",\"name\":\"simply out tours simply out tours\",\"alternateName\":\"Gef\\u00fchrte Touren, Radtouren & Erlebnisse im Ruhrgebiet. Entdecke Industriekultur, Natur und Stadtgeschichte mit simply out tours.\",\"description\":\"gef\\u00fchrte Touren und Sightseeing im Ruhrgebiet\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/simply-out-tours.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Per Bus - simply out tours","description":"Ein \u00dcberblick \u00fcber unsere Touren \"mit dem Bus\" durch das Ruhrgebiet","canonical_url":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/simply-out-tours.de\/en#listItem","position":1,"name":"Zu Hause","item":"https:\/\/simply-out-tours.de\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/#listItem","name":"Touren f\u00fcr private Gruppen"}},{"@type":"ListItem","@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/#listItem","position":2,"name":"Touren f\u00fcr private Gruppen","item":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/#listItem","name":"Per Bus"},"previousItem":{"@type":"ListItem","@id":"https:\/\/simply-out-tours.de\/en#listItem","name":"Zu Hause"}},{"@type":"ListItem","@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/#listItem","position":3,"name":"Per Bus","previousItem":{"@type":"ListItem","@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/#listItem","name":"Touren f\u00fcr private Gruppen"}}]},{"@type":"Organization","@id":"https:\/\/simply-out-tours.de\/en\/#organization","name":"simply out tours - simply out tours","description":"gef\u00fchrte Touren und Sightseeing im Ruhrgebiet - simply out tours","url":"https:\/\/simply-out-tours.de\/en\/","email":"info@simply-out-tours.de","telephone":"+4923433847440","foundingDate":"2022-11-22","numberOfEmployees":{"@type":"QuantitativeValue","value":1},"logo":{"@type":"ImageObject","url":"https:\/\/simply-out-tours.de\/wp-content\/uploads\/2025\/01\/SOT-small.png","@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/#organizationLogo","width":688,"height":413,"caption":"Logo von simply out tours GmbH \u2013 Anbieter f\u00fcr Touren, F\u00fchrungen und Erlebnisse rund um Industriekultur, Stadtgeschichte und Natur im Ruhrgebiet."},"image":{"@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/simplyouttours","https:\/\/instagram.com\/simplyouttours","https:\/\/www.youtube.com\/@simplyouttours.ruhrgebiet","https:\/\/www.linkedin.com\/company\/36574768\/","https:\/\/www.yelp.com\/biz\/simply-out-tours-gmbh-bochum"]},{"@type":"WebPage","@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/#webpage","url":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/","name":"Per Bus - simply out tours","description":"Ein \u00dcberblick \u00fcber unsere Touren \"mit dem Bus\" durch das Ruhrgebiet","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/simply-out-tours.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/#breadcrumblist"},"datePublished":"2024-09-24T07:59:37+01:00","dateModified":"2024-11-19T10:44:38+01:00"},{"@type":"WebSite","@id":"https:\/\/simply-out-tours.de\/en\/#website","url":"https:\/\/simply-out-tours.de\/en\/","name":"simply out tours simply out tours","alternateName":"Gef\u00fchrte Touren, Radtouren & Erlebnisse im Ruhrgebiet. Entdecke Industriekultur, Natur und Stadtgeschichte mit simply out tours.","description":"gef\u00fchrte Touren und Sightseeing im Ruhrgebiet","inLanguage":"en-GB","publisher":{"@id":"https:\/\/simply-out-tours.de\/en\/#organization"}}]}},"aioseo_meta_data":{"post_id":"323","title":null,"description":"Ein \u00dcberblick \u00fcber unsere Touren \"mit dem Bus\" durch das Ruhrgebiet","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-09-24 07:59:37","updated":"2025-06-04 03:45:31","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/simply-out-tours.de\/en\" title=\"Zu Hause\">Zu Hause<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/\" title=\"Touren f\u00fcr private Gruppen\">Touren f\u00fcr private Gruppen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPer Bus\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Zu Hause","link":"https:\/\/simply-out-tours.de\/en"},{"label":"Touren f\u00fcr private Gruppen","link":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/"},{"label":"Per Bus","link":"https:\/\/simply-out-tours.de\/en\/touren-fuer-private-gruppen\/per-bus\/"}],"_links":{"self":[{"href":"https:\/\/simply-out-tours.de\/en\/wp-json\/wp\/v2\/pages\/323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simply-out-tours.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/simply-out-tours.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/simply-out-tours.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simply-out-tours.de\/en\/wp-json\/wp\/v2\/comments?post=323"}],"version-history":[{"count":6,"href":"https:\/\/simply-out-tours.de\/en\/wp-json\/wp\/v2\/pages\/323\/revisions"}],"predecessor-version":[{"id":527,"href":"https:\/\/simply-out-tours.de\/en\/wp-json\/wp\/v2\/pages\/323\/revisions\/527"}],"up":[{"embeddable":true,"href":"https:\/\/simply-out-tours.de\/en\/wp-json\/wp\/v2\/pages\/22"}],"wp:attachment":[{"href":"https:\/\/simply-out-tours.de\/en\/wp-json\/wp\/v2\/media?parent=323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}